{"id":1770,"date":"2022-11-11T09:03:15","date_gmt":"2022-11-11T11:03:15","guid":{"rendered":"https:\/\/saaemb.sp.gov.br\/?p=1770"},"modified":"2022-11-11T09:03:15","modified_gmt":"2022-11-11T11:03:15","slug":"saaemb-distribui-gratuitamente-mudas-de-arvores-em-buritama","status":"publish","type":"post","link":"https:\/\/saaemb.vtec.net.br\/index.php\/2022\/11\/11\/saaemb-distribui-gratuitamente-mudas-de-arvores-em-buritama\/","title":{"rendered":"SAAEMB distribui gratuitamente mudas de \u00e1rvores em Buritama"},"content":{"rendered":"<p>Para incentivar o plantio de \u00e1rvores, o Servi\u00e7o Aut\u00f4nomo de \u00c1gua, Esgoto e Meio Ambiente de Buritama (SAAEMB) conta com o projeto de doa\u00e7\u00e3o de mudas de \u00e1rvores. Durante o cadastro, os interessados recebem orienta\u00e7\u00f5es sobre a melhor muda a ser plantada no local e os cuidados b\u00e1sicos para preservar a esp\u00e9cie.<\/p>\n<p>O objetivo \u00e9 incentivar o aumento da arboriza\u00e7\u00e3o urbana da cidade. Est\u00e3o \u00e0 disposi\u00e7\u00e3o esp\u00e9cies como Oiti e Resed\u00e1. O projeto \u00e9 uma oportunidade para estimular os buritamenses a plantarem \u00e1rvores em cal\u00e7adas e quintais em todo o munic\u00edpio e, assim, ajudar na qualidade do ar na cidade. Nesse ano, de janeiro at\u00e9 novembro, foram doadas cerca de 100 mudas de \u00e1rvores \u00e0 popula\u00e7\u00e3o.<\/p>\n<p>\u00c9 importante o morador se atentar as caracter\u00edsticas das esp\u00e9cies que deseja plantar e verificar se condiz com o espa\u00e7o em fazer o plantio. No ambiente urbano \u00e9 preciso seguir as recomenda\u00e7\u00f5es da prefeitura em rela\u00e7\u00e3o a arboriza\u00e7\u00e3o e ter em mente que as regras s\u00e3o diferentes para locais de passeios p\u00fablicos e \u00e1reas internas de im\u00f3veis.<\/p>\n<p>De acordo com o respons\u00e1vel pela Divis\u00e3o de Saneamento e Meio Ambiente do SAAEMB, Jefferson Pereira da Silva, para retirar a muda de \u00e1rvore, o morador precisa apresentar um documento pessoal e comprovante de endere\u00e7o para preencher o termo de responsabilidade emitido pela autarquia.<\/p>\n<p>\u201cSomente o propriet\u00e1rio ou respons\u00e1vel pode retirar a muda, entre as orienta\u00e7\u00f5es, \u00e9 preciso plantar dentro de 10 dias no endere\u00e7o citado, plantar com a finalidade de arboriza\u00e7\u00e3o urbana, cuidar da esp\u00e9cie e cumprir as normas legais relativas ao corte e poda\u201d, explicou Jefferson ao dizer que ap\u00f3s 15 dias \u00e9 feita uma fiscaliza\u00e7\u00e3o.<\/p>\n<p>Consta na lei n\u00ba 4.492, de 26 de setembro de 2018, no artigo 33, que \u201ca supress\u00e3o de vegetais, nativos ou ex\u00f3ticos, s\u00f3 ser\u00e1 poss\u00edvel quando autorizada pelo SAAEMB, no prazo de 30 (trinta) dias, atrav\u00e9s de expedi\u00e7\u00e3o de documento denominado Autoriza\u00e7\u00e3o Especial de Remo\u00e7\u00e3o de Vegetal\u201d.<\/p>\n<p>Conforme Let\u00edcia Souza Possani, Integrante do Conselho Municipal de Defesa do Meio Ambiente (COMDEMA) e Qu\u00edmica do SAAEMB, ao retirar a muda de \u00e1rvore, o morador assina um terno de compromisso para se comprometer em cuidar e zelar pelo crescimento da esp\u00e9cie. Ela disse tamb\u00e9m que \u00e9 um trabalho lento, mas que poder\u00e1 garantir o aumento da arboriza\u00e7\u00e3o no munic\u00edpio.<\/p>\n<p>\u201cEssa iniciativa \u00e9 muito importante, pois, al\u00e9m de contribuir para o meio ambiente, tamb\u00e9m ajuda a conscientizar as pessoas, sobre a necessidade de participar ativamente da preserva\u00e7\u00e3o da natureza\u201d, enfatizou ainda que a autarquia tamb\u00e9m realiza fiscaliza\u00e7\u00e3o sobre podas dr\u00e1sticas para evitar danos ambientais\u201d, concluiu Let\u00edcia.<\/p>\n<p>Para o diretor do SAAEMB, Jos\u00e9 Eduardo Marins, a doa\u00e7\u00e3o visa promover a preserva\u00e7\u00e3o das florestas e incentivar a prote\u00e7\u00e3o do meio ambiente. \u201cAl\u00e9m de participar de a\u00e7\u00f5es de conscientiza\u00e7\u00e3o, tamb\u00e9m distribu\u00edmos mudas para restaurar o verde, isso atrai p\u00e1ssaros, embeleza o munic\u00edpio e proporciona mais qualidade de vida aos moradores\u201d, concluiu o diretor.<\/p>\n<p><strong>Servi\u00e7o<\/strong><\/p>\n<p>Para mais informa\u00e7\u00f5es, os interessados podem entrar em contato pelo telefone (18) 3691-1306, ou na central de atendimento localizada no SAAEMB, na rua Capit\u00e3o Vicente Gon\u00e7alves, 434, Centro. A retirada das mudas acontece das 8h \u00e0s 12h e das 14h \u00e0s 15h, de segunda a sexta-feira.<\/p>\n<p><strong>\u00a0<\/strong><strong>Publicado:\u00a0<\/strong>11\/11\/2022 \u2013 \u00e0s 08h03<\/p>\n<p><img decoding=\"async\" class=\"alignnone  wp-image-1826 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/saaemb.vtec.net.br\/wp-content\/uploads\/2022\/11\/Objetivos-de-Desenvolvimento-Sustentavel-300x195.png\" alt=\"\" width=\"160\" height=\"104\" \/> <img decoding=\"async\" class=\"alignnone  wp-image-1811 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/saaemb.vtec.net.br\/wp-content\/uploads\/2022\/11\/3.-Saude-e-bem-estar-300x300.png\" alt=\"\" width=\"114\" height=\"114\" \/> <img decoding=\"async\" class=\"alignnone  wp-image-1805 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/saaemb.vtec.net.br\/wp-content\/uploads\/2022\/11\/11.-Cidades-e-comunidades-sustenstaveis-300x300.png\" alt=\"\" width=\"114\" height=\"114\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-1819 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/saaemb.vtec.net.br\/wp-content\/uploads\/2022\/11\/13.-Acao-contra-a-mudanca-global-do-clima-300x300.png\" alt=\"\" width=\"115\" height=\"115\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-1806 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/saaemb.vtec.net.br\/wp-content\/uploads\/2022\/11\/15.-Vida-terrestre-300x300.png\" alt=\"\" width=\"115\" height=\"115\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-1822 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/saaemb.vtec.net.br\/wp-content\/uploads\/2022\/11\/17.-Parcerias-e-meios-de-implementacao-300x300.png\" alt=\"\" width=\"115\" height=\"115\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para incentivar o plantio de \u00e1rvores, o Servi\u00e7o Aut\u00f4nomo de \u00c1gua, Esgoto e Meio Ambiente de Buritama (SAAEMB) conta com o projeto de doa\u00e7\u00e3o de mudas de \u00e1rvores. Durante o cadastro, os interessados recebem orienta\u00e7\u00f5es sobre a melhor muda a ser plantada no local e os cuidados b\u00e1sicos para preservar a esp\u00e9cie. O objetivo \u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1771,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-1770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipio-verdeazul-2"],"_links":{"self":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/posts\/1770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/comments?post=1770"}],"version-history":[{"count":0,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/posts\/1770\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/media\/1771"}],"wp:attachment":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/media?parent=1770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/categories?post=1770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/tags?post=1770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}