{"id":1759,"date":"2022-11-03T15:56:54","date_gmt":"2022-11-03T18:56:54","guid":{"rendered":"https:\/\/saaemb.sp.gov.br\/?p=1759"},"modified":"2022-11-03T15:56:54","modified_gmt":"2022-11-03T18:56:54","slug":"defesa-civil-de-sao-paulo-entrega-ponte-em-buritama","status":"publish","type":"post","link":"https:\/\/saaemb.vtec.net.br\/index.php\/2022\/11\/03\/defesa-civil-de-sao-paulo-entrega-ponte-em-buritama\/","title":{"rendered":"Defesa Civil de S\u00e3o Paulo entrega ponte em Buritama"},"content":{"rendered":"<p>A Defesa Civil de S\u00e3o Paulo entregou, em Buritama, travessia na estrada rural BTM-405, localizada na Rodovia Deputado Roberto Rolemberg, km 58, da SP-461, sobre o C\u00f3rrego Palmeiras. A obra foi realizada pelo governo estadual, por meio de conv\u00eanio com a Defesa Civil, ao todo foram investidos R$ 413.992,30.<\/p>\n<p>A estrutura antiga era de madeira e estava danificada pelo tempo de uso. A ponte tem 7 metros de largura e 9,5 metros de comprimento. As aduelas de concreto pr\u00e9-moldado s\u00e3o, ao mesmo tempo, a estrutura da ponte e a galeria para o percurso do C\u00f3rrego Palmeiras.<\/p>\n<p>A inaugura\u00e7\u00e3o contou com a presen\u00e7a do Coordenador Estadual de Prote\u00e7\u00e3o e Defesa Civil, Coronel da Pol\u00edcia Militar, Henguel Ricardo Pereira, do prefeito Rodrigo Zacarias dos Santos, vice-prefeito Luciano Cesar Batista, do presidente do Conselho Municipal de Defesa Civil (COMDEC), Giancarlo Sanches Mestriner, autoridades, vereadores, diretores e representantes da Defesa Civil municipal.<\/p>\n<p>O coronel Henguel informou que a obra ir\u00e1 aquecer a economia do munic\u00edpio. \u201cNos \u00faltimos anos conseguimos firmar muitos conv\u00eanios com as cidades. A travessia \u00e9 importante para o transporte escolar, ajuda a salvar vidas porque encurta a dist\u00e2ncia e beneficia toda a popula\u00e7\u00e3o. Estamos felizes por mais essa conquista\u201d, explicou.<\/p>\n<p>De acordo com o prefeito Rodrigo, a ponte vai melhorar a mobilidade entre os munic\u00edpios e facilitar o escoamento de gr\u00e3os e gado. \u201cAgradecemos a Defesa Civil pela conquista. Com a obra inaugurada, \u00e9 poss\u00edvel diminuir o percurso que girava em torno de 40 km, contando ida e volta. Por essa estrada passa o transporte de gr\u00e3os, gado, cana de a\u00e7\u00facar, \u00f4nibus escolar. Mais uma vez tenho que ressaltar a dignidade que o governo estadual tem com o munic\u00edpio de Buritama\u201d, disse.<\/p>\n<p>Para o vice-prefeito Luciano, o investimento deve beneficiar os produtores rurais e o transporte de alunos. \u201cUma conquista muito importante para o nosso munic\u00edpio. Batalhamos bastante para que isso se tornasse realidade. Gra\u00e7as ao trabalho da nossa equipe, da Defesa Civil e do governo estadual, foi poss\u00edvel alcan\u00e7ar mais essa obra para o munic\u00edpio\u201d, enfatizou.<\/p>\n<p>Conforme Giancarlo, o investimento diminuir\u00e1 o trajeto de motoristas. \u201cAgradecemos a todos que se empenharam para que o projeto fosse aprovado em S\u00e3o Paulo. Com a ponte ficar\u00e1 mais f\u00e1cil o escoamento de produtos e tamb\u00e9m garante mais seguran\u00e7a para quem depende dessa estrada. \u00c9 um projeto muito importante que foi inaugurado em nosso munic\u00edpio\u201d, sintetizou ao citar que essa obra \u00e9 uma conquista da administra\u00e7\u00e3o, por meio da Defesa Civil.<\/p>\n<p>Segundo o presidente da C\u00e2mara, Carlos Alberto dos Santos, a inaugura\u00e7\u00e3o marca uma importante conquista para o munic\u00edpio. \u201c\u00c9 uma alegria receber todos que contribu\u00edram com essa obra, isso demonstra muito claro o caminho que est\u00e1 tomando nossa cidade. O agroneg\u00f3cio precisava e vem de encontro com a necessidade do munic\u00edpio\u201d, finalizou o vereador.<\/p>\n<p><strong>Publicado: <\/strong>03\/10\/2022 \u2013 \u00e0s 15h56<\/p>\n<p><img decoding=\"async\" class=\"alignnone  wp-image-1826 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/saaemb.vtec.net.br\/wp-content\/uploads\/2022\/11\/Objetivos-de-Desenvolvimento-Sustentavel-300x195.png\" alt=\"\" width=\"183\" height=\"119\" \/> <img decoding=\"async\" class=\"alignnone  wp-image-1815 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/saaemb.vtec.net.br\/wp-content\/uploads\/2022\/11\/8.-Trabalho-decente-e-crescimento-economico-300x300.png\" alt=\"\" width=\"119\" height=\"119\" \/> <img decoding=\"async\" class=\"alignnone  wp-image-1816 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/saaemb.vtec.net.br\/wp-content\/uploads\/2022\/11\/9.-Industria-Inovacao-e-Infraestrutura-300x300.png\" alt=\"\" width=\"121\" height=\"121\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Defesa Civil de S\u00e3o Paulo entregou, em Buritama, travessia na estrada rural BTM-405, localizada na Rodovia Deputado Roberto Rolemberg, km 58, da SP-461, sobre o C\u00f3rrego Palmeiras. A obra foi realizada pelo governo estadual, por meio de conv\u00eanio com a Defesa Civil, ao todo foram investidos R$ 413.992,30. A estrutura antiga era de madeira [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1760,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-1759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/posts\/1759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/comments?post=1759"}],"version-history":[{"count":0,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/posts\/1759\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/media\/1760"}],"wp:attachment":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/media?parent=1759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/categories?post=1759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/tags?post=1759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}