{"id":1280,"date":"2018-04-26T14:14:00","date_gmt":"2018-04-26T17:14:00","guid":{"rendered":"http:\/\/www.saaemb.sp.gov.br\/site\/?p=1280"},"modified":"2018-04-26T14:14:00","modified_gmt":"2018-04-26T17:14:00","slug":"saaemb-realiza-reparos-em-cavaletes-para-evitar-desperdicio-de-agua","status":"publish","type":"post","link":"https:\/\/saaemb.vtec.net.br\/index.php\/2018\/04\/26\/saaemb-realiza-reparos-em-cavaletes-para-evitar-desperdicio-de-agua\/","title":{"rendered":"SAAEMB realiza reparos em cavaletes para evitar desperd\u00edcio de \u00e1gua"},"content":{"rendered":"<p>O SAAEMB (Servi\u00e7o Aut\u00f4nomo de \u00c1gua, Esgoto e Meio Ambiente) realiza por m\u00eas cerca de 20 consertos de cavaletes nas resid\u00eancias de Buritama. A a\u00e7\u00e3o consiste em reparar vazamentos no cavalete que liga a tubula\u00e7\u00e3o da casa a rede de distribui\u00e7\u00e3o de \u00e1gua onde \u00e9 instalado o hidr\u00f4metro. Em m\u00e9dia um vazamento na conex\u00e3o gera 60 gotas por minuto, s\u00e3o 4,32 litros de \u00e1gua por dia, no m\u00eas o desperd\u00edcio \u00e9 de 129,6 litros.<br \/>\nTodos os servi\u00e7os de manuten\u00e7\u00e3o s\u00e3o feitos sem custos aos contribuintes. A cobran\u00e7a acontece caso seja utilizado algum material ou trocado um equipamento durante o trabalho. A autarquia conta com sete encanadores e o respons\u00e1vel pela equipe \u00e9 o servidor Eglyer Humberto Rosa.<br \/>\n\u201cCom o hidr\u00f4metro voc\u00ea consegue controlar o consumo de \u00e1gua na sua resid\u00eancia, podendo estimar quanto vai gastar e tamb\u00e9m se a sua instala\u00e7\u00e3o est\u00e1 com vazamento. Geralmente os vazamentos s\u00e3o constatados nas conex\u00f5es do cavalete\u201d, explicou Rosa.<br \/>\nA qu\u00edmica Let\u00edcia Possani frisou que o uso racional da \u00e1gua diminui a perca de \u00e1gua tratada. O resultado \u00e9 visto no final do m\u00eas com economia na conta, al\u00e9m da preserva\u00e7\u00e3o dos recursos h\u00eddricos. \u00c9 importante manter o bom funcionamento do cavalete e hidr\u00f4metro, assim como da caixa d\u2019\u00e1gua, torneiras, chuveiros e toda tubula\u00e7\u00e3o da casa, consertando poss\u00edveis vazamentos internos e ainda garantir acesso com seguran\u00e7a dos funcion\u00e1rios que fazem a leitura do rel\u00f3gio\u201d, concluiu<br \/>\nSegundo o diretor do SAAEMB, Jo\u00e3o Fermino Falleiros, os cavaletes est\u00e3o sob os cuidados dos contribuintes. Ele explicou que somente funcion\u00e1rios da autarquia podem realizar manuten\u00e7\u00e3o no cavalete ou hidr\u00f4metro. \u201cO morador pode ser penalizado se violar o sistema, conforme prev\u00ea a legisla\u00e7\u00e3o\u201d, disse e acrescentou que \u201cao detectar o vazamento, o contribuinte deve ligar no servi\u00e7o de \u00e1gua para que seja feito o reparo\u201d.<br \/>\nO SAAEMB realiza durante o ano a\u00e7\u00f5es de conscientiza\u00e7\u00e3o. S\u00e3o enviados comunicados na conta de \u00e1gua e site, distribu\u00eddos panfletos e s\u00e3o desenvolvidos trabalhos de educa\u00e7\u00e3o ambiental nas escolas municipais. A autarquia fica na rua Capit\u00e3o Vicente Goncalves, 434, atende de segunda a sexta-feira, das 8h \u00e0s 17h. Informa\u00e7\u00f5es: (18) 3691-1306.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O SAAEMB (Servi\u00e7o Aut\u00f4nomo de \u00c1gua, Esgoto e Meio Ambiente) realiza por m\u00eas cerca de 20 consertos de cavaletes nas resid\u00eancias de Buritama. A a\u00e7\u00e3o consiste em reparar vazamentos no cavalete que liga a tubula\u00e7\u00e3o da casa a rede de distribui\u00e7\u00e3o de \u00e1gua onde \u00e9 instalado o hidr\u00f4metro. Em m\u00e9dia um vazamento na conex\u00e3o gera [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1275,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"_links":{"self":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/posts\/1280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/comments?post=1280"}],"version-history":[{"count":0,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/posts\/1280\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/media\/1275"}],"wp:attachment":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/media?parent=1280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/categories?post=1280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/tags?post=1280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}