{"id":1260,"date":"2018-03-22T18:29:29","date_gmt":"2018-03-22T21:29:29","guid":{"rendered":"http:\/\/www.saaemb.sp.gov.br\/site\/?p=1260"},"modified":"2018-03-22T18:29:29","modified_gmt":"2018-03-22T21:29:29","slug":"saaemb-faz-homenagem-ex-prefeito-camilo-piazzalunga","status":"publish","type":"post","link":"https:\/\/saaemb.vtec.net.br\/index.php\/2018\/03\/22\/saaemb-faz-homenagem-ex-prefeito-camilo-piazzalunga\/","title":{"rendered":"Saaemb faz homenagem a ex-prefeito Camilo Piazzalunga"},"content":{"rendered":"<p>O Saaemb (Servi\u00e7o Aut\u00f4nomo de \u00c1gua, Esgoto e Meio Ambiente) realizou no s\u00e1bado (27), homenagem ao ex-prefeito Camilo Piazzalunga que administrou Buritama entre 1965 a 1969. O evento contou com o prefeito Rodrigo Zacarias dos Santos, vereadores da legisla\u00e7\u00e3o passada e atual, funcion\u00e1rios da autarquia e familiares.<br \/>\nCamilo Piazzalunga nasceu em Gaspar Lopes, Distrito de Alfenas-MG, chegou em Buritama em 1958. Estabeleceu-se com a fam\u00edlia e instalou na \u00e9poca um latic\u00ednio, gerando empregos. Os produtos fabricados chegaram na d\u00e9cada de 60 em S\u00e3o Paulo. Ele tamb\u00e9m foi vereador em duas legislaturas.<br \/>\nEntre seus projetos, idealizou e construiu o asilo S\u00e3o Camilo de Leles. Participou tamb\u00e9m da cria\u00e7\u00e3o e instala\u00e7\u00e3o do clube recreativo e esteve ainda na diretoria da Santa Casa de Buritama. Camilo ajudou e contribuiu para o desenvolvimento do munic\u00edpio. Em 1985, recebeu pelo decreto legislativo, o t\u00edtulo de cidad\u00e3o buritamense.<br \/>\nDe acordo com o Governo do Munic\u00edpio de Buritama, na administra\u00e7\u00e3o do prefeito Rodrigo Zacarias dos Santos, a homenagem mostra o quanto o ex-prefeito Camilo fez pelo munic\u00edpio. \u201cFicamos honrados com este reconhecimento pelo feito Jo\u00e3o Falleiros do Saaemb e \u00e9 importante valorizar as pessoas que lutaram por fazer de nossa cidade um local bom para morar\u201d, disse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Saaemb (Servi\u00e7o Aut\u00f4nomo de \u00c1gua, Esgoto e Meio Ambiente) realizou no s\u00e1bado (27), homenagem ao ex-prefeito Camilo Piazzalunga que administrou Buritama entre 1965 a 1969. O evento contou com o prefeito Rodrigo Zacarias dos Santos, vereadores da legisla\u00e7\u00e3o passada e atual, funcion\u00e1rios da autarquia e familiares. Camilo Piazzalunga nasceu em Gaspar Lopes, Distrito de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1250,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"_links":{"self":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/posts\/1260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/comments?post=1260"}],"version-history":[{"count":0,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/posts\/1260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/media\/1250"}],"wp:attachment":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/media?parent=1260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/categories?post=1260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/tags?post=1260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}