{"id":1211,"date":"2017-08-01T17:44:44","date_gmt":"2017-08-01T20:44:44","guid":{"rendered":"http:\/\/www.saaemb.sp.gov.br\/site\/?p=1211"},"modified":"2017-08-01T17:44:44","modified_gmt":"2017-08-01T20:44:44","slug":"saaemb-realiza-tratamento-do-esgoto","status":"publish","type":"post","link":"https:\/\/saaemb.vtec.net.br\/index.php\/2017\/08\/01\/saaemb-realiza-tratamento-do-esgoto\/","title":{"rendered":"SAAEMB realiza tratamento do esgoto"},"content":{"rendered":"<p>Em Buritama, todo o esgoto produzido no munic\u00edpio \u00e9 100% tratado, o que oferece mais qualidade de vida a popula\u00e7\u00e3o<br \/>\nO SAAEMB (Servi\u00e7o Aut\u00f4nomo de \u00c1gua, Esgoto e Meio Ambiente) de Buritama realiza na ETE (Esta\u00e7\u00e3o de Tratamento de Esgoto) o controle de todo dejeto coletado atrav\u00e9s do emiss\u00e1rio localizado na Rua dos Pereiras e destinado para a lagoa de tratamento, localizada na estrada vicinal Ant\u00f4nio Alves Teixeira &#8211; Km 2.<br \/>\nO esgoto, ao chegar \u00e0 lagoa de tratamento, passa por um pr\u00e9-tratamento que consiste em retirar todo material s\u00f3lido e areia, e no decorrer do seu processo ocorre toda a degrada\u00e7\u00e3o da mat\u00e9ria org\u00e2nica, envolvendo a participa\u00e7\u00e3o de bact\u00e9rias facultativas e estritamente anaer\u00f3bias, reduzindo EM at\u00e9 60% da carga org\u00e2nica j\u00e1 na primeira fase. Depois o esgoto \u00e9 destinado para a segunda lagoa: o tratamento \u00e9 predominantemente biol\u00f3gico, removendo as impurezas por meio de rea\u00e7\u00f5es bioqu\u00edmicas realizadas pelos micro-organismos.<br \/>\nSegundo a qu\u00edmica da autarquia, Let\u00edcia Possani, o tratamento biol\u00f3gico \u00e9 a forma mais eficiente de remo\u00e7\u00e3o da mat\u00e9ria org\u00e2nica dos esgotos e apresenta baixo custo. \u201cIsso diminui muito a incid\u00eancia de doen\u00e7as com contamina\u00e7\u00e3o h\u00eddrica. Cerca de 50 tipos de infec\u00e7\u00f5es podem ser transmitidos para uma pessoa, atrav\u00e9s de \u00e1gua contaminada, do alimento e do solo\u201d disse, ao acrescentar que outra importante raz\u00e3o para tratar o esgoto \u00e9 a preserva\u00e7\u00e3o do meio ambiente. \u201cAs subst\u00e2ncias presentes no esgoto diminuem a concentra\u00e7\u00e3o de oxig\u00eanio dissolvido na \u00e1gua, causando a morte de peixes e outros organismos aqu\u00e1ticos, al\u00e9m do escurecimento e do mau cheiro\u201d, afirma.<br \/>\nDe acordo com o diretor do SAAEMB Jo\u00e3o Fermino Falleiros, o tratamento do esgoto \u00e9 um requisito para adquirir o selo Munic\u00edpio Verde Azul destinado \u00e0s cidades que atendem \u00e0s exig\u00eancias do programa. \u201cA falta de tratamento dos esgotos e condi\u00e7\u00f5es adequadas de saneamento podem contribuir para a prolifera\u00e7\u00e3o de in\u00fameras doen\u00e7as causadas por parasitas e infec\u00e7\u00f5es\u201d, comentou.<br \/>\nLet\u00edcia disse que o SAAEMB coleta e trata todo o esgoto gerado pelo munic\u00edpio. A autarquia monitora e controla o lan\u00e7amento do esgoto que \u00e9 feito no c\u00f3rrego Palmeiras. S\u00e3o feitas an\u00e1lises para atender os padr\u00f5es estabelecidos pela legisla\u00e7\u00e3o. \u201cO compromisso \u00e9 n\u00e3o alterar a classe ou a natureza do rio receptor\u201d, elenca.<br \/>\nO diretor frisou que a popula\u00e7\u00e3o tamb\u00e9m pode contribuir com a qualidade do servi\u00e7o prestado. Ele citou algumas a\u00e7\u00f5es: n\u00e3o jogar material s\u00f3lido na rede de esgoto para evitar o entupimento; usar detergentes biodegrad\u00e1veis; ter caixa de gordura nas resid\u00eancias; n\u00e3o canalizar \u00e1gua da chuva na rede de esgoto; tudo isso pode entupir e romper as redes e pode tamb\u00e9m transbordar os po\u00e7os de visita e causar o retorno de esgoto nas casas; al\u00e9m de evitar descartar produtos t\u00f3xicos como querosene, gasolina ou thinner para n\u00e3o contaminar o curso da \u00e1gua receptora.<br \/>\nEm Buritama, conforme Let\u00edcia, todo o esgoto produzido no munic\u00edpio \u00e9 100% tratado. \u201cSomente os loteamentos \u00e0 beira do rio ainda possuem fossas s\u00e9pticas que ao serem limpas t\u00eam o material recebido e tratado na lagoa de tratamento\u201d, explica.<br \/>\n<strong>Lagoa de tratamento<\/strong><br \/>\n<strong>\u00a0<\/strong>O SAAEMB (Servi\u00e7o Aut\u00f4nomo de \u00c1gua, Esgoto e Meio Ambiente) de Buritama recebeu recurso do FEHIDRO (Fundo Estadual de Recursos H\u00eddricos) para o desassoreamento da primeira lagoa na esta\u00e7\u00e3o de tratamento do munic\u00edpio. A obra contribuir\u00e1 para a melhoria do servi\u00e7o prestado e beneficiar\u00e1 a qualidade da \u00e1gua descartada que ser\u00e1 mais segura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em Buritama, todo o esgoto produzido no munic\u00edpio \u00e9 100% tratado, o que oferece mais qualidade de vida a popula\u00e7\u00e3o O SAAEMB (Servi\u00e7o Aut\u00f4nomo de \u00c1gua, Esgoto e Meio Ambiente) de Buritama realiza na ETE (Esta\u00e7\u00e3o de Tratamento de Esgoto) o controle de todo dejeto coletado atrav\u00e9s do emiss\u00e1rio localizado na Rua dos Pereiras e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1213,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"_links":{"self":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/posts\/1211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/comments?post=1211"}],"version-history":[{"count":0,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/posts\/1211\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/media\/1213"}],"wp:attachment":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/media?parent=1211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/categories?post=1211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/tags?post=1211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}