{"id":1095,"date":"2017-07-02T21:49:27","date_gmt":"2017-07-03T00:49:27","guid":{"rendered":"http:\/\/www.saaemb.sp.gov.br\/site\/?p=1095"},"modified":"2017-07-02T21:49:27","modified_gmt":"2017-07-03T00:49:27","slug":"saaemb-realiza-limpeza-higienizacao-e-desinfeccao-dos-reservatorios-em-buritama","status":"publish","type":"post","link":"https:\/\/saaemb.vtec.net.br\/index.php\/2017\/07\/02\/saaemb-realiza-limpeza-higienizacao-e-desinfeccao-dos-reservatorios-em-buritama\/","title":{"rendered":"SAAEMB realiza limpeza, higieniza\u00e7\u00e3o e desinfec\u00e7\u00e3o dos reservat\u00f3rios em Buritama"},"content":{"rendered":"<p><!-- \/ Yoast SEO plugin. --><\/p>\n<div id=\"page\" class=\"hfeed site\">\n<div id=\"page\" class=\"hfeed site\">\n<div class=\"site_main_container\">\n<section class=\"site_content container\">\n<div class=\"site_content_wrapper\">\n<div class=\"site_content_inner_container row\">\n<div id=\"post-3113\" class=\"content_wrapper single_content_wrapper post-3113 post type-post status-publish format-standard has-post-thumbnail hentry category-saaemb\">\n<article class=\"blog_post clearfix\">\n<div class=\"blog_post_content post_content\">\n<div class=\"post_content_inner_wrapper content_inner_wrapper entry-content\">\nO SAAEMB (Servi\u00e7o Aut\u00f4nomo de \u00c1gua, Esgoto e Meio ambiente de Buritama) realizou limpeza, higieniza\u00e7\u00e3o e desinfec\u00e7\u00e3o dos reservat\u00f3rios. O trabalho \u00e9 feito com base na RDC (Resolu\u00e7\u00e3o de Diretoria Colegiada) n\u00ba 91 de 30 de junho de 2016. O documento estabelece crit\u00e9rios e procedimentos para o controle sanit\u00e1rio da \u00e1gua destinada ao consumo humano proveniente de sistema de abastecimento de \u00e1gua. Abrange ainda todas as empresas que prestam servi\u00e7os de abastecimento e determina boas pr\u00e1ticas sanit\u00e1rias na opera\u00e7\u00e3o e manuten\u00e7\u00e3o do sistema. O trabalho aconteceu de 11 a 14 de junho.<br \/>\nDe acordo com o diretor do SAAEMB, Jo\u00e3o Fermino Falleiros, os sete reservat\u00f3rios receberam a manuten\u00e7\u00e3o. Os sistemas de abastecimento est\u00e3o localizados nos seguintes pontos: estrada municipal dos Teixeiras, o qual abastece 70% da popula\u00e7\u00e3o; n\u00facleo da Cesp que atende as glebas 10, 11 e 13 e toda regi\u00e3o do Jardim Buriti, Jardim Itaparica (2), parque industrial e os conjuntos habitacionais Hor\u00e1cio Rodrigues Goulart e Rubens Ant\u00f4nio Severino.<br \/>\n\u201cO objetivo do trabalho \u00e9 controlar e manter a qualidade da \u00e1gua ofertada \u00e0 popula\u00e7\u00e3o. Toda \u00e1gua fornecida coletivamente deve ser submetida a processo de desinfec\u00e7\u00e3o, concebido e operado de forma a garantir o padr\u00e3o microbiol\u00f3gico e f\u00edsico-qu\u00edmico de potabilidade da \u00e1gua\u201d, disse o diretor.<br \/>\nSegundo a qu\u00edmica da autarquia, Let\u00edcia Possani, a \u00e1gua para consumo humano, destinado \u00e0 ingest\u00e3o, prepara\u00e7\u00e3o e produ\u00e7\u00e3o de alimentos, higiene pessoal, independente da sua origem precisa estar no padr\u00e3o de potabilidade estabelecido em legisla\u00e7\u00e3o espec\u00edfica e que n\u00e3o ofere\u00e7a riscos \u00e0 sa\u00fade.<br \/>\n\u201cAs boas pr\u00e1ticas sanit\u00e1rias \u00e9 um conjunto de procedimentos para garantir a qualidade sanit\u00e1ria de um produto ou servi\u00e7o, cuja efic\u00e1cia e efetividade devem ser avaliadas por meio de inspe\u00e7\u00e3o ou investiga\u00e7\u00e3o\u201d disse ao concluir que as atividades exercidas pelo SAAEMB acontecem de forma cont\u00ednua e \u00e9 importante para assegurar a qualidade do abastecimento de \u00e1gua.\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O SAAEMB (Servi\u00e7o Aut\u00f4nomo de \u00c1gua, Esgoto e Meio ambiente de Buritama) realizou limpeza, higieniza\u00e7\u00e3o e desinfec\u00e7\u00e3o dos reservat\u00f3rios. O trabalho \u00e9 feito com base na RDC (Resolu\u00e7\u00e3o de Diretoria Colegiada) n\u00ba 91 de 30 de junho de 2016. O documento estabelece crit\u00e9rios e procedimentos para o controle sanit\u00e1rio da \u00e1gua destinada ao consumo humano [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1204,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"_links":{"self":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/posts\/1095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/comments?post=1095"}],"version-history":[{"count":0,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/posts\/1095\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/media\/1204"}],"wp:attachment":[{"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/media?parent=1095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/categories?post=1095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saaemb.vtec.net.br\/index.php\/wp-json\/wp\/v2\/tags?post=1095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}